{"id":45768,"date":"2020-11-09T07:00:00","date_gmt":"2020-11-09T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/covid-19-response-at-peru-201109\/"},"modified":"2026-02-04T08:01:27","modified_gmt":"2026-02-04T08:01:27","slug":"covid-19-response-at-peru-201109","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/","title":{"rendered":"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg\" alt=\"\" class=\"wp-image-45759\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">El 19 de noviembre, los miembros de la Fundaci\u00f3n Internacional WeLoveU (denominada en lo sucesivo \u201cWeLoveU\u201d) en Lima, Per\u00fa, donaron 1000 mascarillas a la Comisar\u00eda de Independencia. Fue para expresar gratitud a los polic\u00edas quienes estuvieron trabajando duro para la prevenci\u00f3n de la pandemia y la seguridad de los ciudadanos, sin descanso en medio de la propagaci\u00f3n de la COVID-19. Nueve miembros de WeLoveU y cinco oficiales de polic\u00eda participaron en la ceremonia de entrega.<\/p>\n<p class=\"wp-block-paragraph\">Los propios miembros inspeccionaron todas las mascarillas para cambiar las defectuosas y empacar cuidadosamente las mejores en cajas. Despu\u00e9s, pusieron pegatinas en las cajas con un mensaje: \u201cPolic\u00edas, gracias por sus esfuerzos para combatir la COVID-19\u201d. De este modo, expresaron su gratitud a los oficiales por sus arduos esfuerzos d\u00eda y noche para prevenir la propagaci\u00f3n de la enfermedad infecciosa.<\/p>\n<p class=\"wp-block-paragraph\">Los miembros gritaron: \u201cWe Love You\u201d, a los oficiales que participaron de la ceremonia, y luego: \u201c\u00a1\u00c1nimo! \u00a1\u00c1nimo! \u00a1\u00c1nimo!\u201d Los oficiales respondieron con aplausos a los miembros, expresando su agradecimiento por las mascarillas.<\/p>\n","protected":false},"excerpt":{"rendered":"El 19 de noviembre, los miembros de la Fundaci\u00f3n Internacional WeLoveU (denominada en lo sucesivo \u201cWeLoveU\u201d) en Lima, Per\u00fa, donaron 1000 mascarillas a la Comisar\u00eda de Independencia. Fue para expresar gratitud a los polic\u00edas quienes estuvieron trabajando duro para la prevenci\u00f3n de la pandemia y la seguridad de los ciudadanos, sin descanso en medio de&#8230;","protected":false},"author":11,"featured_media":45763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119,55,58,69],"tags":[],"class_list":["post-45768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emergency-relief","category-sdgs","category-news","category-sdgs-good-health-well-being"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"El 19 de noviembre, los miembros de la Fundaci\u00f3n Internacional WeLoveU (denominada en lo sucesivo \u201cWeLoveU\u201d) en Lima, Per\u00fa, donaron 1000 mascarillas a la Comisar\u00eda de Independencia. Fue para expresar gratitud a los polic\u00edas quienes estuvieron trabajando duro para la prevenci\u00f3n de la pandemia y la seguridad de los ciudadanos, sin descanso en medio de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T08:01:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/\"},\"author\":{\"name\":\"l ss\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"headline\":\"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa\",\"datePublished\":\"2020-11-09T07:00:00+00:00\",\"dateModified\":\"2026-02-04T08:01:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/\"},\"wordCount\":189,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_covid_19_response_at_peru_201109.jpg\",\"articleSection\":[\"Ayuda en casos de emergencia\",\"Con los ODS\",\"Noticias de proyectos\",\"Salud y bienestar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/\",\"name\":\"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_covid_19_response_at_peru_201109.jpg\",\"datePublished\":\"2020-11-09T07:00:00+00:00\",\"dateModified\":\"2026-02-04T08:01:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_covid_19_response_at_peru_201109.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_covid_19_response_at_peru_201109.jpg\",\"width\":1080,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/covid-19-response-at-peru-201109\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/","og_locale":"es_ES","og_type":"article","og_title":"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa - Fundaci\u00f3n Internacional WeLoveU","og_description":"El 19 de noviembre, los miembros de la Fundaci\u00f3n Internacional WeLoveU (denominada en lo sucesivo \u201cWeLoveU\u201d) en Lima, Per\u00fa, donaron 1000 mascarillas a la Comisar\u00eda de Independencia. Fue para expresar gratitud a los polic\u00edas quienes estuvieron trabajando duro para la prevenci\u00f3n de la pandemia y la seguridad de los ciudadanos, sin descanso en medio de...","og_url":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2020-11-09T07:00:00+00:00","article_modified_time":"2026-02-04T08:01:27+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/"},"author":{"name":"l ss","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"headline":"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa","datePublished":"2020-11-09T07:00:00+00:00","dateModified":"2026-02-04T08:01:27+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/"},"wordCount":189,"image":{"@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg","articleSection":["Ayuda en casos de emergencia","Con los ODS","Noticias de proyectos","Salud y bienestar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/","url":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/","name":"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg","datePublished":"2020-11-09T07:00:00+00:00","dateModified":"2026-02-04T08:01:27+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_covid_19_response_at_peru_201109.jpg","width":1080,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/covid-19-response-at-peru-201109\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"Donaci\u00f3n de mascarillas a la Comisar\u00eda de Independencia en Lima, Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/45768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=45768"}],"version-history":[{"count":1,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/45768\/revisions"}],"predecessor-version":[{"id":45771,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/45768\/revisions\/45771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/45763"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=45768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=45768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=45768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}