{"id":30014,"date":"2004-07-25T07:00:00","date_gmt":"2004-07-25T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/2004-sketch-contest\/"},"modified":"2026-01-23T08:50:35","modified_gmt":"2026-01-23T08:50:35","slug":"2004-sketch-contest","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/","title":{"rendered":"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg\" alt=\"\" class=\"wp-image-29981\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg 1920w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg-768x512.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg-1536x1024.jpg 1536w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg-750x500.jpg 750w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Despu\u00e9s del fuerte llueve de la ma\u00f1ana se fue el calor del verano, y hac\u00eda fresco por la tarde. Los ni\u00f1os tendieron papel de dibujo y se concentraron en dibujar. Incluso en un d\u00eda nublado, el sol comenzaba a salir y los p\u00e1jaros y las mariposas volaban en su papel de dibujo.<\/p>\n<h2 class=\"wp-block-heading\">\u201cEl hermoso r\u00edo Jord\u00e1n\u201d, donde las personas comparten lo que tienen con su pr\u00f3jimo<\/h2>\n<p class=\"wp-block-paragraph\">El domingo 25 de julio, se llev\u00f3 a cabo el \u201cConcurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados\u201d en el Parque Jungang ubicado en Bundan-gu, ciudad de Seongnam. Cerca de 3000 miembros de la sucursal de Seongnam de la Fundaci\u00f3n de Bienestar Nueva Vida incluyendo unos 1000 ni\u00f1os participaron en este evento, organizado por la Fundaci\u00f3n de Bienestar Nueva Vida y patrocinado por la Fundaci\u00f3n de Protecci\u00f3n Infantil de Corea, la Red de Transmisi\u00f3n de Areum, y la revista mensual Corea Hoy.<\/p>\n<p class=\"wp-block-paragraph\">Se coloc\u00f3 una caja de recaudaci\u00f3n para ayudar a los ni\u00f1os en la pobreza en la entrada del lugar del evento. Los ni\u00f1os que participaron en el concurso trajeron sus propios tableros de dibujo, crayones pastel, acuarelas, pinceles, paletas y cubetas de agua. Ellos no pasaron de largo la caja de recaudaci\u00f3n, sino pusieron su donaci\u00f3n en ella. No solo los miembros de la fundaci\u00f3n, sino tambi\u00e9n los ciudadanos, que vinieron a pasear con su familia, se detuvieron y participaron voluntariamente en la recaudaci\u00f3n de fondos.<\/p>\n<p class=\"wp-block-paragraph\">La Presidenta Zahng Gil-jah explic\u00f3 el prop\u00f3sito del concurso a los participantes, diciendo: \u201cEste evento se ha preparado para ayudar a los ni\u00f1os que sufren de enfermedades incurables y a los que lo necesitan. Les deseamos que vivan con sue\u00f1os, sin perder la esperanza, incluso bajo situaciones desfavorables\u201d. Tambi\u00e9n nos cont\u00f3 una historia sobre el r\u00edo Jord\u00e1n y el Mar Muerto en el Talmud. La historia se trataba de los dos grandes r\u00edos de Israel: uno de ellos era el Jord\u00e1n cuya agua tiene vida, ya que da tanto como recibe, y el otro era el Mar Muerto, cuyas aguas est\u00e1n muertas, ya que solo recibe sin dar. La presidenta Zahng anim\u00f3 a los miembros: \u201cUstedes son como el hermoso r\u00edo viviente Jord\u00e1n, puesto que se preocupan por su pr\u00f3jimo y comparten lo que tienen con ellos incluso en la recesi\u00f3n econ\u00f3mica actual\u201d. Los miembros comprendieron una vez m\u00e1s la importancia de compartir a trav\u00e9s de su consuelo.<\/p>\n<p class=\"wp-block-paragraph\">En el discurso de felicitaci\u00f3n, el presidente de la Fundaci\u00f3n de Protecci\u00f3n Infantil de Corea, Lee Bae-Keun, apreci\u00f3 mucho el verdadero amor de los miembros de la Fundaci\u00f3n de Bienestar Nueva Vida hacia su pr\u00f3jimo, afirmando: \u201cHay dos caracter\u00edsticas de los miembros de la Fundaci\u00f3n de Bienestar Nueva Vida: el entusiasmo y la sinceridad\u201d. Adem\u00e1s, dijo con respecto al concurso: \u201cLos ni\u00f1os expresan su mundo interior no solo de palabra, sino tambi\u00e9n con sus escritos y dibujos. Es un evento inusual y grandioso que permite a los adultos descubrir el mundo interior de los ni\u00f1os y tambi\u00e9n ayudar a los ni\u00f1os necesitados\u201d.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_02.jpg\" alt=\"\" class=\"wp-image-29982\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_02.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_02-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_02-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, el presidente de Corea Hoy, O Ju-heon, entreg\u00f3 una placa de reconocimiento a la Presidenta Zahng Gil-jah y al Director Kim Joo-cheol respectivamente.<\/p>\n<p class=\"wp-block-paragraph\">La Presidenta Zahng Gil-jah hizo entrega del \u201cFondo de la Esperanza\u201d, con un total de 20 millones de wones a nueve ni\u00f1os que viven en la ciudad de Seongnam: un ni\u00f1o que sufre de c\u00e1ncer infantil, dos hogares sin padres, cinco ni\u00f1os que viven en un hogar monoparental y un ni\u00f1o en extrema pobreza. Los miembros oraron para que los beneficiarios superaran los sufrimientos presentes y tambi\u00e9n estuvieran mejor econ\u00f3mica y mentalmente.<\/p>\n<p class=\"wp-block-paragraph\">Al finalizar la ceremonia oficial, se presentaron diversas actuaciones: una canci\u00f3n del Coro Infantil Nueva Vida, el Samulnori (cuarteto de percusi\u00f3n tradicional) de los ni\u00f1os, un quinteto de instrumentos de viento, un musical infantil&nbsp;<em>La liebre y la tortuga<\/em>, y la representaci\u00f3n de una banda de m\u00fasica. Independientemente de la edad, todos los asistentes se mostraron complacidos con las emocionantes e interesantes actuaciones.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" data-id=\"29983\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_03.jpg\" alt=\"\" class=\"wp-image-29983\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_03.jpg 1920w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_03-768x512.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_03-1536x1024.jpg 1536w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_03-750x500.jpg 750w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29984\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_04.jpg\" alt=\"\" class=\"wp-image-29984\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_04.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_04-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_04-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29986\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_05.jpg\" alt=\"\" class=\"wp-image-29986\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_05.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_05-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_05-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29987\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_06.jpg\" alt=\"\" class=\"wp-image-29987\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_06.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_06-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_06-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\">Un momento feliz en familia<\/h2>\n<p class=\"wp-block-paragraph\">Tras la ceremonia oficial, los miembros almorzaron con su familia. Despu\u00e9s de terminar de almorzar, todos empezaron a dibujar el paisaje que los rodeaba. Los ni\u00f1os dibujaron su mundo interior, a diferencia de los adultos que solamente dibujaban el mundo visible. Los padres estaban sentados junto a sus hijos y los entrenaban en silencio sin escatimar \u00e1nimo y elogio.<\/p>\n<p class=\"wp-block-paragraph\">Park Gyeong-sun (35 a\u00f1os), que guiaba a su hija de siete a\u00f1os, Hyeon-jin, exclam\u00f3: \u201cA mi hija mayor le encanta dibujar. Me complace tener un tiempo \u00fatil con mis hijos a trav\u00e9s de este evento\u201d. Los solicitantes del concurso fueron clasificados por categor\u00edas; ni\u00f1os, estudiantes de secundaria y adultos. Algunas familias participaron en las tres categor\u00edas.<\/p>\n<p class=\"wp-block-paragraph\">La familia de Yedam (7 a\u00f1os) present\u00f3 tres piezas de arte: Yedam pint\u00f3 una tierra de ensue\u00f1o con gorriones, mariposas y abejas volando alrededor; su padre dibuj\u00f3 una bonita acuarela y su madre un hermoso arco\u00edris de siete colores. El padre de Yedam, Kim Yong-hee (32 a\u00f1os), manifest\u00f3: \u201cEste evento me recuerda mis d\u00edas de escuela. Este concurso ser\u00e1 educativo para mi hijo porque todos los miembros de nuestra familia dibujaron juntos y tambi\u00e9n pudimos ayudar a otros amigos necesitados\u201d.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29988\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_07.jpg\" alt=\"\" class=\"wp-image-29988\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_07.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_07-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_07-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29989\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_08.jpg\" alt=\"\" class=\"wp-image-29989\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_08.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_08-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_08-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">Mientras el concurso, un payaso y un pierrot entregaban globos artesanales a los ni\u00f1os, y populares personajes de dibujos animados tambi\u00e9n los hac\u00edan re\u00edr. En una esquina del recinto se llev\u00f3 a cabo el evento \u201cLa Mejor Sonrisa de la Familia\u201d, que consist\u00eda en fotografiar la mejor sonrisa de la familia acompa\u00f1ada de personajes de caricatura, y en la otra esquina la gente formaba una larga fila, esperando participar en la pintura facial.<\/p>\n<p class=\"wp-block-paragraph\">Alrededor de las 3 p. m., los miembros presentaron sus dibujos y limpiaron su entorno. Luego se dirigieron a casa, comentando: \u201cEspero que haya m\u00e1s oportunidades de pasar un momento agradable con la familia y tambi\u00e9n de ayudar a nuestro pr\u00f3jimo necesitado\u201d. Tras su espalda, la luz deslumbrante del sol brillaba desde el cielo mientras las nubes retroced\u00edan.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_09.jpg\" alt=\"\" class=\"wp-image-29990\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_09.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_09-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_09-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"Despu\u00e9s del fuerte llueve de la ma\u00f1ana se fue el calor del verano, y hac\u00eda fresco por la tarde. Los ni\u00f1os tendieron papel de dibujo y se concentraron en dibujar. Incluso en un d\u00eda nublado, el sol comenzaba a salir y los p\u00e1jaros y las mariposas volaban en su papel de dibujo. \u201cEl hermoso r\u00edo&#8230;","protected":false},"author":11,"featured_media":35015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,73,110,81],"tags":[],"class_list":["post-30014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sdgs","category-campaign-news","category-sdgs-peace","category-saving-humanity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s del fuerte llueve de la ma\u00f1ana se fue el calor del verano, y hac\u00eda fresco por la tarde. Los ni\u00f1os tendieron papel de dibujo y se concentraron en dibujar. Incluso en un d\u00eda nublado, el sol comenzaba a salir y los p\u00e1jaros y las mariposas volaban en su papel de dibujo. \u201cEl hermoso r\u00edo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2004-07-25T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T08:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/\"},\"author\":{\"name\":\"l ss\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"headline\":\"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados\",\"datePublished\":\"2004-07-25T07:00:00+00:00\",\"dateModified\":\"2026-01-23T08:50:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/\"},\"wordCount\":1079,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_2004_sketch_contest_01jpg.jpg\",\"articleSection\":[\"Con los ODS\",\"Noticias de campa\u00f1a\",\"Paz, justicia e instituciones s\u00f3lidas\",\"Salvemos a la Humanidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/\",\"name\":\"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_2004_sketch_contest_01jpg.jpg\",\"datePublished\":\"2004-07-25T07:00:00+00:00\",\"dateModified\":\"2026-01-23T08:50:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_2004_sketch_contest_01jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_2004_sketch_contest_01jpg.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/2004-sketch-contest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/","og_locale":"es_ES","og_type":"article","og_title":"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados - Fundaci\u00f3n Internacional WeLoveU","og_description":"Despu\u00e9s del fuerte llueve de la ma\u00f1ana se fue el calor del verano, y hac\u00eda fresco por la tarde. Los ni\u00f1os tendieron papel de dibujo y se concentraron en dibujar. Incluso en un d\u00eda nublado, el sol comenzaba a salir y los p\u00e1jaros y las mariposas volaban en su papel de dibujo. \u201cEl hermoso r\u00edo...","og_url":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2004-07-25T07:00:00+00:00","article_modified_time":"2026-01-23T08:50:35+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/"},"author":{"name":"l ss","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"headline":"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados","datePublished":"2004-07-25T07:00:00+00:00","dateModified":"2026-01-23T08:50:35+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/"},"wordCount":1079,"image":{"@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg","articleSection":["Con los ODS","Noticias de campa\u00f1a","Paz, justicia e instituciones s\u00f3lidas","Salvemos a la Humanidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/","url":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/","name":"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg","datePublished":"2004-07-25T07:00:00+00:00","dateModified":"2026-01-23T08:50:35+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_2004_sketch_contest_01jpg.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/2004-sketch-contest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"Concurso de Dibujo 2004 para Ayudar a los Ni\u00f1os Necesitados"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/30014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=30014"}],"version-history":[{"count":1,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/30014\/revisions"}],"predecessor-version":[{"id":30018,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/30014\/revisions\/30018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/35015"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=30014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=30014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=30014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}