{"id":29385,"date":"2010-02-05T07:00:00","date_gmt":"2010-02-05T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/blood-drive-daejeon-2010\/"},"modified":"2026-01-28T01:11:38","modified_gmt":"2026-01-28T01:11:38","slug":"blood-drive-daejeon-2010","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/","title":{"rendered":"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Internacional WeLoveU organiz\u00f3 la Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer, frente al pabell\u00f3n de pediatr\u00eda del Hospital de la Universidad de Chungnam el viernes 5 de febrero por segunda vez desde el a\u00f1o pasado. La donaci\u00f3n de sangre fue copatrocinada por la Fundaci\u00f3n Internacional WeLoveU y el Hospital de la Universidad de Chungnam, y asistieron al evento cerca de 750 personas, incluyendo miembros de la fundaci\u00f3n, ciudadanos, personal del hospital y visitantes.<\/p>\n<p class=\"wp-block-paragraph\">Lee Wu-seop, representante de la sucursal de Daejeon de la Fundaci\u00f3n Internacional WeLoveU, dijo: \u201cLa donaci\u00f3n de sangre es como el amor incondicional de una madre. Ahora nuestra sociedad necesita urgentemente esta clase de amor. As\u00ed como el amor y la actividad voluntaria de muchas personas salv\u00f3 a la gente moribunda de los efectos del terremoto de Hait\u00ed, nosotros realizamos este evento, confiando en que ser\u00e1 una esperanza para los pacientes con c\u00e1ncer\u201d.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_01.jpg\" alt=\"\" class=\"wp-image-29343\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_01.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_01-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_01-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Song Si-heon, director del Hospital de la Universidad de Chungnam, expres\u00f3: \u201cAunque la ciencia haya avanzado, no hay nada que pueda reemplazar a la sangre humana. Agradezco a muchos de los miembros que han venido a pesar del clima fr\u00edo para ayudar a los pacientes que lo necesitan\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Cada verano e invierno, es dif\u00edcil suministrar sangre a los pacientes. Especialmente en este invierno fue m\u00e1s dif\u00edcil debido a la epidemia del virus de la gripe A desde octubre hasta diciembre, las fuertes nevadas y la ola de fr\u00edo de enero. Explicando la situaci\u00f3n reciente, Kim Cheol-su, gerente de la Secci\u00f3n de Planificaci\u00f3n del Banco de Sangre de Daejeon Chungnam de la Cruz Roja Nacional de Corea, dijo: \u201cPedimos ayuda a la Fundaci\u00f3n Internacional WeLoveU porque era dif\u00edcil conseguir sangre. Su donaci\u00f3n de sangre ser\u00e1 de gran ayuda\u201d.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg\" alt=\"\" class=\"wp-image-29344\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">La donaci\u00f3n de sangre se desarroll\u00f3 desde las 9:30 a. m. hasta las 5 p. m. en tres veh\u00edculos de sangre de la Cruz Roja Nacional de Corea. El examen m\u00e9dico para los donantes fue muy estricto, a fin de suministrar a los pacientes sangre segura y saludable. Los miembros que resultaron aptos en el examen de hemoglobina, llenaron su historia cl\u00ednica. Los que pasaron diversos ex\u00e1menes de historia cl\u00ednica, condici\u00f3n f\u00edsica, consumo de drogas e identificaci\u00f3n, pudieron donar sangre.<\/p>\n<p class=\"wp-block-paragraph\">Este d\u00eda, cerca de 200 miembros que hab\u00edan pasado el examen m\u00e9dico donaron sangre. 200 certificados de donaci\u00f3n de sangre se presentaron en el Hospital de la Universidad de Chungnam para ser utilizados para los pacientes con c\u00e1ncer que ten\u00edan dificultad en recibir tratamiento m\u00e9dico debido a problemas econ\u00f3micos.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_03.jpg\" alt=\"\" class=\"wp-image-29345\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_03.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_03-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_03-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Gang Hye-gyeong, miembro de la fundaci\u00f3n de 44 a\u00f1os, de Cheon-dong, Dong-gu, manifest\u00f3: \u201cAunque hubiera querido donar sangre, no pod\u00eda debido a mi mala salud. Por eso cuidaba mi salud constantemente y al fin he donado sangre hoy\u201d. Shin O-yeong, una miembro de 30 a\u00f1os, de Bongsan-dong, Yuseong-gu, dijo: \u201cMi sobrino tuvo una operaci\u00f3n por una enfermedad card\u00edaca cuando era muy joven. En aquel momento supe que los certificados de donaci\u00f3n de sangre fueron una gran ayuda. Desde entonces, he donado sangre constantemente, comprendiendo a los donatarios\u201d. Yim Hyang-hye, de 40 a\u00f1os, de Seonhwa-dong, Jung-gu, que particip\u00f3 voluntariamente cuando se enter\u00f3 del evento a trav\u00e9s de una miembro, expres\u00f3: \u201cLlegu\u00e9 aqu\u00ed porque pens\u00e9 que era algo bueno. Estoy feliz de ayudar a los pacientes\u201d. Ella a\u00f1adi\u00f3 que quer\u00eda participar nuevamente en la campa\u00f1a de donaci\u00f3n de sangre.<\/p>\n<p class=\"wp-block-paragraph\">Incluso los miembros que iban a trabajar, participaron en el evento a la hora del almuerzo o despu\u00e9s de pedir la comprensi\u00f3n de sus jefes. Jin Sa-cheol, un miembro de 42 a\u00f1os, de Mannyeon-dong, Seo-gu, dijo: \u201cEs m\u00e1s satisfactorio donar sangre que dar una ayuda f\u00edsica\u201d.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29346\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_04.jpg\" alt=\"\" class=\"wp-image-29346\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_04.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_04-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_04-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"29347\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_05.jpg\" alt=\"\" class=\"wp-image-29347\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_05.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_05-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_05-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">En esta donaci\u00f3n de sangre, no solo los miembros de la Fundaci\u00f3n Internacional WeLoveU, sino tambi\u00e9n el personal del hospital y los visitantes, participaron en practicar el amor al pr\u00f3jimo. Lo m\u00e1s sorprendente fue que hubo una persona que quer\u00eda ser miembro de la Fundaci\u00f3n Internacional WeLoveU para seguir participando en la donaci\u00f3n de sangre. Aunque hac\u00eda mucho fr\u00edo, todos los participantes sintieron la calidez de amor y estuvieron determinados a compartir el gozo del amor y la vida con su pr\u00f3jimo continuamente.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2010\/02\/thum_blood_drive_daejeon_2010_06.jpg\" alt=\"\" class=\"wp-image-29391\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2010\/02\/thum_blood_drive_daejeon_2010_06.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2010\/02\/thum_blood_drive_daejeon_2010_06-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2010\/02\/thum_blood_drive_daejeon_2010_06-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"La Fundaci\u00f3n Internacional WeLoveU organiz\u00f3 la Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer, frente al pabell\u00f3n de pediatr\u00eda del Hospital de la Universidad de Chungnam el viernes 5 de febrero por segunda vez desde el a\u00f1o pasado. La donaci\u00f3n de sangre fue copatrocinada por la Fundaci\u00f3n Internacional WeLoveU y el Hospital de&#8230;","protected":false},"author":11,"featured_media":34963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,73,110,84],"tags":[],"class_list":["post-29385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sdgs","category-campaign-news","category-sdgs-peace","category-saving-lives"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"La Fundaci\u00f3n Internacional WeLoveU organiz\u00f3 la Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer, frente al pabell\u00f3n de pediatr\u00eda del Hospital de la Universidad de Chungnam el viernes 5 de febrero por segunda vez desde el a\u00f1o pasado. La donaci\u00f3n de sangre fue copatrocinada por la Fundaci\u00f3n Internacional WeLoveU y el Hospital de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-05T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T01:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/\"},\"author\":{\"name\":\"l ss\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"headline\":\"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon\",\"datePublished\":\"2010-02-05T07:00:00+00:00\",\"dateModified\":\"2026-01-28T01:11:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/\"},\"wordCount\":761,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_daejeon_2010_02.jpg\",\"articleSection\":[\"Con los ODS\",\"Noticias de campa\u00f1a\",\"Paz, justicia e instituciones s\u00f3lidas\",\"Salvemos la Vida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/\",\"name\":\"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_daejeon_2010_02.jpg\",\"datePublished\":\"2010-02-05T07:00:00+00:00\",\"dateModified\":\"2026-01-28T01:11:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_daejeon_2010_02.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_daejeon_2010_02.jpg\",\"width\":1170,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-daejeon-2010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/","og_locale":"es_ES","og_type":"article","og_title":"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon - Fundaci\u00f3n Internacional WeLoveU","og_description":"La Fundaci\u00f3n Internacional WeLoveU organiz\u00f3 la Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer, frente al pabell\u00f3n de pediatr\u00eda del Hospital de la Universidad de Chungnam el viernes 5 de febrero por segunda vez desde el a\u00f1o pasado. La donaci\u00f3n de sangre fue copatrocinada por la Fundaci\u00f3n Internacional WeLoveU y el Hospital de...","og_url":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2010-02-05T07:00:00+00:00","article_modified_time":"2026-01-28T01:11:38+00:00","og_image":[{"width":1170,"height":550,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/"},"author":{"name":"l ss","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"headline":"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon","datePublished":"2010-02-05T07:00:00+00:00","dateModified":"2026-01-28T01:11:38+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/"},"wordCount":761,"image":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg","articleSection":["Con los ODS","Noticias de campa\u00f1a","Paz, justicia e instituciones s\u00f3lidas","Salvemos la Vida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/","url":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/","name":"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg","datePublished":"2010-02-05T07:00:00+00:00","dateModified":"2026-01-28T01:11:38+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_daejeon_2010_02.jpg","width":1170,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-daejeon-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"Campa\u00f1a de Donaci\u00f3n de Sangre para los Pacientes con C\u00e1ncer en la sucursal de Daejeon"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/29385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=29385"}],"version-history":[{"count":3,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/29385\/revisions"}],"predecessor-version":[{"id":29393,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/29385\/revisions\/29393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/34963"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=29385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=29385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=29385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}