{"id":28533,"date":"2010-12-05T07:00:00","date_gmt":"2010-12-05T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/clean-world-planting-lima-peru\/"},"modified":"2026-01-30T08:52:56","modified_gmt":"2026-01-30T08:52:56","slug":"clean-world-planting-lima-peru","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/","title":{"rendered":"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Hay un creciente inter\u00e9s en el medio ambiente mundial que sufre por la contaminaci\u00f3n ambiental y el calentamiento global. En consonancia con esto, la Fundaci\u00f3n Internacional WeLoveU (en adelante \u201cWeLoveU\u201d) est\u00e1 realizando activamente el \u201cMovimiento Clean World\u201d. Este movimiento es una campa\u00f1a de limpieza ambiental que los miembros est\u00e1n llevando a cabo un\u00e1nimemente con el objetivo de conservar una naturaleza hermosa.<\/p>\n<p class=\"wp-block-paragraph\">El 5 de diciembre de 2010, los miembros de la sucursal de Lima, Per\u00fa, llevaron a cabo una campa\u00f1a de plantaci\u00f3n de \u00e1rboles con el lema: \u201cLos \u00e1rboles son la esperanza de vida\u201d, como parte del Movimiento Clean World. La campa\u00f1a se realiz\u00f3 en el Parque \u201cLos Olivos de Pro\u201d y 220 miembros de WeLoveU plantaron 100 \u00e1rboles.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_01.jpg\" alt=\"\" class=\"wp-image-28479\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_01.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_01-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_01-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Desde temprano en la ma\u00f1ana, los miembros participaron activamente en la campa\u00f1a, llevando palas y azadas. Prepararon voluntariamente escobas y bolsas de basura para limpiar las zonas aleda\u00f1as.<\/p>\n<p class=\"wp-block-paragraph\">El Sr. Freddy, quien coment\u00f3 que no hab\u00eda tenido tiempo para participar en actividades de voluntariado debido a su trabajo, sonri\u00f3 ampliamente y dijo: \u201cMe un\u00ed a la campa\u00f1a de plantaci\u00f3n de \u00e1rboles junto con mi esposa e hijo. Como dividimos el trabajo y cooperamos entre nosotros, pudimos terminarla pronto\u201d.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1464\" height=\"1098\" data-id=\"28481\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_02.jpg\" alt=\"\" class=\"wp-image-28481\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_02.jpg 1464w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_02-768x576.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_02-667x500.jpg 667w\" sizes=\"auto, (max-width: 1464px) 100vw, 1464px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1485\" height=\"1114\" data-id=\"28484\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_03.jpg\" alt=\"\" class=\"wp-image-28484\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_03.jpg 1485w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_03-768x576.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_03-667x500.jpg 667w\" sizes=\"auto, (max-width: 1485px) 100vw, 1485px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">Una integrante llamada Melisa coment\u00f3: \u201cPlant\u00e9 cada \u00e1rbol con el coraz\u00f3n de una madre. Plantar 100 \u00e1rboles es significativo, pero lo m\u00e1s importante es cuidarlos para que crezcan sanos y fuertes\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Los miembros tambi\u00e9n recibieron una respuesta entusiasta por parte de los ciudadanos y los funcionarios de la Municipalidad de Los Olivos.<\/p>\n<p class=\"wp-block-paragraph\">Richardson Armas Asmad, representante distrital de Los Olivos, Lima, Per\u00fa, expres\u00f3 su gratitud, enfatizando: \u201cTendremos un futuro brillante solo cuando amemos y conservemos nuestro medio ambiente. En ese sentido, estoy muy agradecido con la Fundaci\u00f3n WeLoveU y con Corea por animar a la gente a plantar \u00e1rboles mediante esta maravillosa campa\u00f1a\u201d.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1390\" height=\"1043\" data-id=\"28485\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_04.jpg\" alt=\"\" class=\"wp-image-28485\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_04.jpg 1390w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_04-768x576.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_04-666x500.jpg 666w\" sizes=\"auto, (max-width: 1390px) 100vw, 1390px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1464\" height=\"1098\" data-id=\"28486\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_05.jpg\" alt=\"\" class=\"wp-image-28486\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_05.jpg 1464w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_05-768x576.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_05-667x500.jpg 667w\" sizes=\"auto, (max-width: 1464px) 100vw, 1464px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">Mar\u00eda Blanca, funcionaria de la Divisi\u00f3n Ambiental de la Municipalidad de Los Olivos, expres\u00f3 su sorpresa por el alto \u00edndice de participaci\u00f3n de los j\u00f3venes. Llena de admiraci\u00f3n, dijo: \u201cEn estos d\u00edas, los j\u00f3venes est\u00e1n muy ocupados disfrutando de sus actividades favoritas como los deportes; pero los j\u00f3venes de la Fundaci\u00f3n WeLoveU se ofrecen como voluntarios para conservar el medio ambiente. Es muy impresionante\u201d.<\/p>\n<p class=\"wp-block-paragraph\">El director de la sucursal de WeLoveU en el Per\u00fa manifest\u00f3: \u201cAhora el Per\u00fa est\u00e1 sufriendo por una contaminaci\u00f3n ambiental extensiva debido a las pol\u00edticas de crecimiento econ\u00f3mico a corto plazo. Como el crecimiento econ\u00f3mico tiene prioridad sobre la conservaci\u00f3n del medio ambiente, los peruanos tienen relativamente poco inter\u00e9s en la protecci\u00f3n ambiental. Es por eso que la Fundaci\u00f3n WeLoveU toma la iniciativa animando a las personas a interesarse en el medio ambiente a trav\u00e9s de esta campa\u00f1a\u201d.<\/p>\n<p class=\"wp-block-paragraph\">La sucursal de WeLoveU en Lima, Per\u00fa, prevee seguir llevando a cabo el Movimiento Clean World y la Campa\u00f1a de Donaci\u00f3n de Sangre a nivel nacional en cooperaci\u00f3n con todas las sucursales del Per\u00fa.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg\" alt=\"\" class=\"wp-image-28487\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"Hay un creciente inter\u00e9s en el medio ambiente mundial que sufre por la contaminaci\u00f3n ambiental y el calentamiento global. En consonancia con esto, la Fundaci\u00f3n Internacional WeLoveU (en adelante \u201cWeLoveU\u201d) est\u00e1 realizando activamente el \u201cMovimiento Clean World\u201d. Este movimiento es una campa\u00f1a de limpieza ambiental que los miembros est\u00e1n llevando a cabo un\u00e1nimemente con el&#8230;","protected":false},"author":6,"featured_media":34950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,73,113,87],"tags":[],"class_list":["post-28533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sdgs","category-campaign-news","category-sdgs-environmental-protection","category-saving-the-earth"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"Hay un creciente inter\u00e9s en el medio ambiente mundial que sufre por la contaminaci\u00f3n ambiental y el calentamiento global. En consonancia con esto, la Fundaci\u00f3n Internacional WeLoveU (en adelante \u201cWeLoveU\u201d) est\u00e1 realizando activamente el \u201cMovimiento Clean World\u201d. Este movimiento es una campa\u00f1a de limpieza ambiental que los miembros est\u00e1n llevando a cabo un\u00e1nimemente con el...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-05T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T08:52:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\ud669 \uc815\ubbfc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\ud669 \uc815\ubbfc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/\"},\"author\":{\"name\":\"\ud669 \uc815\ubbfc\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/e280e94e44b58dbecee233d984090d5e\"},\"headline\":\"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles\",\"datePublished\":\"2010-12-05T07:00:00+00:00\",\"dateModified\":\"2026-01-30T08:52:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/\"},\"wordCount\":530,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_clean_world_planting_lima_peru_06.jpg\",\"articleSection\":[\"Con los ODS\",\"Noticias de campa\u00f1a\",\"Proteccion medioambiental\",\"Salvemos la Tierra\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/\",\"name\":\"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_clean_world_planting_lima_peru_06.jpg\",\"datePublished\":\"2010-12-05T07:00:00+00:00\",\"dateModified\":\"2026-01-30T08:52:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/e280e94e44b58dbecee233d984090d5e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_clean_world_planting_lima_peru_06.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_clean_world_planting_lima_peru_06.jpg\",\"width\":1170,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/clean-world-planting-lima-peru\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/e280e94e44b58dbecee233d984090d5e\",\"name\":\"\ud669 \uc815\ubbfc\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/","og_locale":"es_ES","og_type":"article","og_title":"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles - Fundaci\u00f3n Internacional WeLoveU","og_description":"Hay un creciente inter\u00e9s en el medio ambiente mundial que sufre por la contaminaci\u00f3n ambiental y el calentamiento global. En consonancia con esto, la Fundaci\u00f3n Internacional WeLoveU (en adelante \u201cWeLoveU\u201d) est\u00e1 realizando activamente el \u201cMovimiento Clean World\u201d. Este movimiento es una campa\u00f1a de limpieza ambiental que los miembros est\u00e1n llevando a cabo un\u00e1nimemente con el...","og_url":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2010-12-05T07:00:00+00:00","article_modified_time":"2026-01-30T08:52:56+00:00","og_image":[{"width":1170,"height":550,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg","type":"image\/jpeg"}],"author":"\ud669 \uc815\ubbfc","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\ud669 \uc815\ubbfc","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/"},"author":{"name":"\ud669 \uc815\ubbfc","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/e280e94e44b58dbecee233d984090d5e"},"headline":"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles","datePublished":"2010-12-05T07:00:00+00:00","dateModified":"2026-01-30T08:52:56+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/"},"wordCount":530,"image":{"@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg","articleSection":["Con los ODS","Noticias de campa\u00f1a","Proteccion medioambiental","Salvemos la Tierra"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/","url":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/","name":"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg","datePublished":"2010-12-05T07:00:00+00:00","dateModified":"2026-01-30T08:52:56+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/e280e94e44b58dbecee233d984090d5e"},"breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_clean_world_planting_lima_peru_06.jpg","width":1170,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/clean-world-planting-lima-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"Movimiento Clean World de la Sucursal de Lima, Per\u00fa \u2014 Campa\u00f1a de Plantaci\u00f3n de \u00c1rboles"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/e280e94e44b58dbecee233d984090d5e","name":"\ud669 \uc815\ubbfc"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/28533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=28533"}],"version-history":[{"count":3,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/28533\/revisions"}],"predecessor-version":[{"id":31324,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/28533\/revisions\/31324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/34950"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=28533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=28533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=28533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}