{"id":27581,"date":"2009-06-04T07:00:00","date_gmt":"2009-06-04T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/blood-drive-for-cancer-patients\/"},"modified":"2026-03-13T07:33:32","modified_gmt":"2026-03-13T07:33:32","slug":"blood-drive-for-cancer-patients","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/","title":{"rendered":"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1275\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg\" alt=\"\" class=\"wp-image-27578\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg 1920w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01-768x510.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01-1536x1020.jpg 1536w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01-753x500.jpg 753w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">El 4 de junio, la Fundaci\u00f3n Internacional WeLoveU llev\u00f3 a cabo la \u201cCampa\u00f1a de Donaci\u00f3n de Sangre para Pacientes con C\u00e1ncer\u201d frente al pabell\u00f3n infantil del Hospital de la Universidad de Chungnam. Este evento fue copatrocinado por la Fundaci\u00f3n Internacional WeLoveU y el Centro de C\u00e1ncer de Daejeon del Hospital de la Universidad de Chungnam, y tuvo mucho \u00e9xito gracias a la participaci\u00f3n positiva de m\u00e1s de 500 miembros de la sucursal de Daejeon de la Fundaci\u00f3n Internacional WeLoveU.<\/p>\n<p class=\"wp-block-paragraph\">Lee Woo-seop, representante de la sucursal de Daejeon de la Fundaci\u00f3n Internacional WeLoveU, expres\u00f3: \u201cLa fundaci\u00f3n realiza diversas actividades de servicio voluntario. Entre ellas, la donaci\u00f3n de sangre es un proyecto muy significativo para salvar a las personas que est\u00e1n muriendo. Esta vez, los miembros de la sucursal de Daejeon donaron sangre\u201d. Park Jong-woo, jefe del Centro de C\u00e1ncer de Daejeon del Hospital de la Universidad de Chungnam, quien hizo un gran esfuerzo para llevar a cabo esta campa\u00f1a de donaci\u00f3n de sangre con la Cruz Roja Nacional Coreana, expres\u00f3 su gratitud: \u201cAprecio la participaci\u00f3n y cooperaci\u00f3n sincera de todos los miembros. Nos aseguraremos de utilizarla para salvar vidas sin desperdiciar ni una gota de su preciosa sangre\u201d. Kim Cheol-su, gerente de la Secci\u00f3n de Planeamiento del Banco de Sangre de Daejeon-Chungnam de la Cruz Roja Nacional de Corea, expres\u00f3: \u201cLas escuelas, las bases militares y muchas organizaciones donan sangre, pero durante las vacaciones de verano e invierno nos resulta dif\u00edcil suministrar sangre a los pacientes. En estos tiempos dif\u00edciles para conseguir sangre, si un grupo social voluntario dona sangre como ustedes, llega a ser de gran ayuda\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Tres veh\u00edculos de donaci\u00f3n de sangre de la Cruz Roja Nacional de Corea llegaron a la universidad en la ma\u00f1ana, y la campa\u00f1a se desarroll\u00f3 en completo orden desde las 10 a. m. hasta las 4 p. m. Despu\u00e9s de escuchar el prop\u00f3sito de la campa\u00f1a y c\u00f3mo donar, solo los voluntarios, quienes obtuvieron resultados normales en los ex\u00e1menes de hemoglobina, llenaron los expedientes m\u00e9dicos. El examen m\u00e9dico, realizado por medio de una entrevista antes de la extracci\u00f3n de sangre, fue muy estricto, con el est\u00e1ndar de pa\u00edses avanzados, ya que deb\u00eda considerarse la salud de los donantes y suministrarse sangre segura a los donatarios. A trav\u00e9s de diversos ex\u00e1menes, como ex\u00e1menes de presi\u00f3n sangu\u00ednea, condici\u00f3n corporal e historias cl\u00ednicas, solo los que aprobaron pudieron donar sangre.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27560\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_02.jpg\" alt=\"\" class=\"wp-image-27560\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_02.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_02-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_02-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27561\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_03.jpg\" alt=\"\" class=\"wp-image-27561\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_03.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_03-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_03-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27562\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_04.jpg\" alt=\"\" class=\"wp-image-27562\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_04.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_04-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_04-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">Los miembros que no pudieron donar sangre regresaron a sus hogares sinti\u00e9ndose apenados. Ellos dijeron: \u201cSin duda donar\u00e9 sangre la pr\u00f3xima vez despu\u00e9s de cuidar mi salud\u201d. Ese d\u00eda, 198 miembros que aprobaron los controles m\u00e9dicos, donaron sangre y otorgaron sus certificados de donaci\u00f3n de sangre al Centro de C\u00e1ncer de Daejeon del Hospital de la Universidad de Chungnam. Se espera que estos certificados de donaci\u00f3n se utilicen para los pacientes con c\u00e1ncer que no han recibido tratamiento m\u00e9dico debido a dificultades econ\u00f3micas.<\/p>\n<p class=\"wp-block-paragraph\">Kim Hee-yeong, una miembro de la fundaci\u00f3n (33 a\u00f1os, de Panam-dong, dong-gu, Daejeon), declar\u00f3: \u201cHace dos a\u00f1os, cuando mi padre fue hospitalizado debido al c\u00e1ncer, fue muy dif\u00edcil econ\u00f3micamente conseguir una transfusi\u00f3n de sangre. En el pasado, mi salud no era lo suficientemente buena para donar sangre, pero hoy pude hacerlo. Estoy muy contenta de estar sana y poder donar sangre. Pensando que cuando dono sangre cordialmente esta tambi\u00e9n es \u00fatil para los donatarios, particip\u00e9 con alegr\u00eda\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Park Seong-a, una miembro, (36 a\u00f1os, de Deogam-dong, Daedeok-gu, Daejeon), dijo: \u201cCuando di a luz a mi tercer hijo, sangr\u00e9 mucho. Con la donaci\u00f3n de sangre de alguien, pude superar la crisis. Estoy feliz de compartir lo que he recibido con alguien m\u00e1s a trav\u00e9s de este evento\u201d. Lee Jung-hyeon, una miembro (63 a\u00f1os, de Seonhwa-dong, Jung-gu, Daejeon), dijo: \u201cSoy muy afortunada y me siento orgullosa de poder donar mi sangre a los 63 a\u00f1os. Espero que los pacientes se recuperen pronto a trav\u00e9s de nuestra peque\u00f1a pr\u00e1ctica de amor\u201d.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27563\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_05.jpg\" alt=\"\" class=\"wp-image-27563\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_05.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_05-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_05-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"550\" data-id=\"27564\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_06.jpg\" alt=\"\" class=\"wp-image-27564\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_06.jpg 1170w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_06-768x361.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_06-860x404.jpg 860w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">En esta campa\u00f1a de donaci\u00f3n de sangre, no solo los miembros de la Fundaci\u00f3n Internacional WeLoveU, sino tambi\u00e9n el personal del hospital y los visitantes participaron para salvar vidas. Y tambi\u00e9n, el \u00edndice de solicitantes aptos fue alto; esto demuestra que la mente agradable y los h\u00e1bitos de vida saludables de los miembros de la fundaci\u00f3n, quienes participaron positivamente en las actividades de servicio voluntario, son la base para formar personas y sociedades saludables.<\/p>\n<p class=\"wp-block-paragraph\">Lee Woo-seop, representante de la sucursal de Daejeon de la Fundaci\u00f3n Internacional WeLoveU, expres\u00f3: \u201cEstamos planificando realizar campa\u00f1as continuas de donaci\u00f3n de sangre en la \u00e9poca de escasez de suministro de sangre\u201d. Hoy los voluntarios de la sucursal de Daejeon sintieron felicidad y val\u00eda, y se comprometieron a tomar la iniciativa en iluminar a muchas personas para que presten atenci\u00f3n al valor de la vida y participen en la donaci\u00f3n de sangre.<\/p>\n","protected":false},"excerpt":{"rendered":"El 4 de junio, la Fundaci\u00f3n Internacional WeLoveU llev\u00f3 a cabo la \u201cCampa\u00f1a de Donaci\u00f3n de Sangre para Pacientes con C\u00e1ncer\u201d frente al pabell\u00f3n infantil del Hospital de la Universidad de Chungnam. Este evento fue copatrocinado por la Fundaci\u00f3n Internacional WeLoveU y el Centro de C\u00e1ncer de Daejeon del Hospital de la Universidad de Chungnam,&#8230;","protected":false},"author":11,"featured_media":27578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,73,110,84],"tags":[],"class_list":["post-27581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sdgs","category-campaign-news","category-sdgs-peace","category-saving-lives"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"El 4 de junio, la Fundaci\u00f3n Internacional WeLoveU llev\u00f3 a cabo la \u201cCampa\u00f1a de Donaci\u00f3n de Sangre para Pacientes con C\u00e1ncer\u201d frente al pabell\u00f3n infantil del Hospital de la Universidad de Chungnam. Este evento fue copatrocinado por la Fundaci\u00f3n Internacional WeLoveU y el Centro de C\u00e1ncer de Daejeon del Hospital de la Universidad de Chungnam,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-04T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T07:33:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/\"},\"author\":{\"name\":\"l ss\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"headline\":\"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d\",\"datePublished\":\"2009-06-04T07:00:00+00:00\",\"dateModified\":\"2026-03-13T07:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/\"},\"wordCount\":879,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_for_cancer_patients_01.jpg\",\"articleSection\":[\"Con los ODS\",\"Noticias de campa\u00f1a\",\"Paz, justicia e instituciones s\u00f3lidas\",\"Salvemos la Vida\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/\",\"name\":\"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_for_cancer_patients_01.jpg\",\"datePublished\":\"2009-06-04T07:00:00+00:00\",\"dateModified\":\"2026-03-13T07:33:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_for_cancer_patients_01.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/thum_blood_drive_for_cancer_patients_01.jpg\",\"width\":1920,\"height\":1275},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/blood-drive-for-cancer-patients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d - Fundaci\u00f3n Internacional WeLoveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d - Fundaci\u00f3n Internacional WeLoveU","og_description":"El 4 de junio, la Fundaci\u00f3n Internacional WeLoveU llev\u00f3 a cabo la \u201cCampa\u00f1a de Donaci\u00f3n de Sangre para Pacientes con C\u00e1ncer\u201d frente al pabell\u00f3n infantil del Hospital de la Universidad de Chungnam. Este evento fue copatrocinado por la Fundaci\u00f3n Internacional WeLoveU y el Centro de C\u00e1ncer de Daejeon del Hospital de la Universidad de Chungnam,...","og_url":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2009-06-04T07:00:00+00:00","article_modified_time":"2026-03-13T07:33:32+00:00","og_image":[{"width":1920,"height":1275,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/"},"author":{"name":"l ss","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"headline":"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d","datePublished":"2009-06-04T07:00:00+00:00","dateModified":"2026-03-13T07:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/"},"wordCount":879,"image":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg","articleSection":["Con los ODS","Noticias de campa\u00f1a","Paz, justicia e instituciones s\u00f3lidas","Salvemos la Vida"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/","url":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/","name":"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg","datePublished":"2009-06-04T07:00:00+00:00","dateModified":"2026-03-13T07:33:32+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/10\/thum_blood_drive_for_cancer_patients_01.jpg","width":1920,"height":1275},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/blood-drive-for-cancer-patients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u201cCampa\u00f1a de donaci\u00f3n de sangre para pacientes con c\u00e1ncer\u201d"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/27581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=27581"}],"version-history":[{"count":2,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/27581\/revisions"}],"predecessor-version":[{"id":240300,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/27581\/revisions\/240300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/27578"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=27581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=27581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=27581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}