{"id":241018,"date":"2024-09-05T08:00:00","date_gmt":"2024-09-05T08:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/giving-hope-wildfires-chile-240905\/"},"modified":"2026-04-10T01:56:27","modified_gmt":"2026-04-10T01:56:27","slug":"giving-hope-wildfires-chile-240905","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/","title":{"rendered":"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A principios de febrero, incendios forestales devastaron varias \u00e1reas en Valpara\u00edso, Chile. La sequ\u00eda prolongada, las temperaturas altas y los vientos fuertes alimentaron la propagaci\u00f3n r\u00e1pida de incendios que alcanzaron \u00e1reas residenciales. M\u00e1s de 16 000 edificios, incluyendo viviendas, fueron da\u00f1ados, y m\u00e1s de 150 personas perdieron sus vidas. Aproximadamente una tercera parte de Vi\u00f1a del Mar fue severamente da\u00f1ada por las llamas.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_01.jpg\" alt=\"\" class=\"wp-image-35239\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_01.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_01-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_01-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Un pueblo en ladera en proceso de reparaci\u00f3n y reconstrucci\u00f3n<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">Se declar\u00f3 un estado nacional de emergencia, y las v\u00edctimas han estado haciendo esfuerzos para recuperar sus vidas cotidianas con apoyo del gobierno, autoridades locales y ciudadanos. Sin embargo, queda mucho por hacer antes de que la ciudad pueda recuperarse completamente.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_02.jpg\" alt=\"\" class=\"wp-image-35240\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_02.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_02-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_02-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Recuperaci\u00f3n lenta alrededor de cocinas comunitarias<\/figcaption><\/figure>\n<p class=\"wp-block-paragraph\">M\u00e1s de 8 000 v\u00edctimas a\u00fan dependen de las comidas gratuitas operadas por gobiernos locales en Vi\u00f1a del Mar.<\/p>\n<p class=\"wp-block-paragraph\">Para apoyar la r\u00e1pida recuperaci\u00f3n de las v\u00edctimas, WeLoveU prepar\u00f3 500 cajas de suministros alimenticios esenciales, incluyendo arroz, harina, frijoles, espagueti, sal, az\u00facar y aceite de cocina.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35241\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_03.jpg\" alt=\"\" class=\"wp-image-35241\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_03.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_03-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_03-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35242\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_04.jpg\" alt=\"\" class=\"wp-image-35242\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_04.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_04-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_04-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">El 17 de julio, los miembros de WeLoveU visitaron cuatro cocinas comunitarias en Vi\u00f1a del Mar para ayudar con la preparaci\u00f3n de comidas y consolar a las v\u00edctimas. Al d\u00eda siguiente, 500 cajas de alimentos fueron entregadas a 46 cocinas a trav\u00e9s del ayuntamiento. El 5 de septiembre, se proporcion\u00f3 apoyo adicional en ropa en Cancha el tamarugal, un centro log\u00edstico y de apoyo administrado por la ciudad.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Servicio de Voluntariado en Cocina Comunitaria<\/strong><\/h2>\n<h3 class=\"wp-block-heading\">17 de julio<\/h3>\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35243\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_05.jpg\" alt=\"\" class=\"wp-image-35243\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_05.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_05-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_05-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35244\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_06.jpg\" alt=\"\" class=\"wp-image-35244\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_06.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_06-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_06-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35245\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_07.jpg\" alt=\"\" class=\"wp-image-35245\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_07.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_07-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_07-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35246\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_08.jpg\" alt=\"\" class=\"wp-image-35246\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_08.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_08-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_08-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\"><strong>Entrega de Cajas de Alimentos<\/strong><\/h2>\n<h3 class=\"wp-block-heading\">18 de julio<\/h3>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large width-100\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"35247\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_09.jpg\" alt=\"\" class=\"wp-image-35247\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_09.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_09-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_09-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1032\" height=\"645\" data-id=\"35248\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_10.jpg\" alt=\"\" class=\"wp-image-35248\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_10.jpg 1032w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_10-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_10-800x500.jpg 800w\" sizes=\"auto, (max-width: 1032px) 100vw, 1032px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1032\" height=\"645\" data-id=\"35249\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_11.jpg\" alt=\"\" class=\"wp-image-35249\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_11.jpg 1032w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_11-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_11-800x500.jpg 800w\" sizes=\"auto, (max-width: 1032px) 100vw, 1032px\" \/><\/figure>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1032\" height=\"645\" data-id=\"35250\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_12.jpg\" alt=\"\" class=\"wp-image-35250\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_12.jpg 1032w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_12-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_12-800x500.jpg 800w\" sizes=\"auto, (max-width: 1032px) 100vw, 1032px\" \/><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\"><strong>Donaci\u00f3n de Ropa<\/strong><\/h2>\n<h3 class=\"wp-block-heading\">5 de septiembre<\/h3>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_13.jpg\" alt=\"\" class=\"wp-image-35251\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_13.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_13-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_13-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Ver a los vecinos sonre\u00edr mientras recib\u00edan comidas que fueron preparadas de todo coraz\u00f3n por los miembros trajo alegr\u00eda tambi\u00e9n a los voluntarios. Las v\u00edctimas y los voluntarios se abrazaron y se confortaron mutuamente, ofreciendo \u00e1nimo y esperando una r\u00e1pida vuelta a la vida normal.<\/p>\n<p class=\"wp-block-paragraph\">La Alcaldesa Macarena Ripamonti expres\u00f3 su gratitud a WeLoveU, diciendo: \u201cEsta donaci\u00f3n es de gran ayuda para las v\u00edctimas del enorme incendio forestal\u201d.<\/p>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_14.jpg\" alt=\"\" class=\"wp-image-35252 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_14.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_14-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cCuando toda la monta\u00f1a ardi\u00f3 en nuestro vecindario, m\u00e1s de 350 familias fueron desplazadas. Al principio, serv\u00edamos comidas a 600 personas desde esta cocina comunal, pero con el apoyo disminuyendo, ahora solo podemos servir a 200 personas. Al recibir estos suministros de alimentos hoy, estuve muy feliz. Gracias a esto, podemos proporcionar alimentos a 160 o 180 familias durante un mes. Agradecemos a los j\u00f3venes (miembros de WeLoveU) que vinieron a nosotros. Esta cocina se llama \u2018Fe y Esperanza\u2019, y fiel a su nombre, nunca perderemos nuestra fe y esperanza. Espero que m\u00e1s personas se presenten para apoyarnos. Muchas gracias\u201d.<\/p>\n<p class=\"cite wp-block-paragraph\">Jessica Rivera, Representante Residente de Loma La Torre<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_15.jpg\" alt=\"\" class=\"wp-image-35253 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_15.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_15-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cEstoy muy contenta de que nos hayan recordado y venido a visitarnos. Pocas personas nos visitan, salvo funcionarios municipales ocasionales, ya que es una zona alejada. Con el apoyo disminuyendo, dirigir esta cocina comunal se ha vuelto dif\u00edcil. Ahora abrimos solo un d\u00eda s\u00ed y un d\u00eda no, pues solo nos queda un poco de pasta y arroz. Muchas gracias por el apoyo de WeLoveU. Conozco sus esfuerzos y pasi\u00f3n por ayudarnos. Estoy muy feliz y profundamente agradecida\u201d.<\/p>\n<p class=\"cite wp-block-paragraph\">Cristina, Personal de Cocina Comunitaria<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_16.jpg\" alt=\"\" class=\"wp-image-35254 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_16.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905_16-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cAl principio, serv\u00edamos a 100 personas a la vez, pero ahora son alrededor de 80. Incluso los vecinos que sol\u00edan traer verduras han dejado de hacerlo, y dependemos \u00fanicamente del apoyo del ayuntamiento. Muchas cocinas comunales en otras zonas han cerrado por falta de recursos, pero nosotros seguimos perseverando. Estoy agradecida a WeLoveU por visitarnos. Gracias a su apoyo, podemos continuar con este trabajo. Muchas gracias\u201d.<\/p>\n<p class=\"cite wp-block-paragraph\">Personal de Cocina Comunitaria<\/p>\n<\/div>\n<\/div>\n<p class=\"wp-block-paragraph\">Esperamos que este apoyo haya tra\u00eddo consuelo y esperanza a los vecinos afectados por el desastre. Aplaudimos la r\u00e1pida recuperaci\u00f3n de la vida cotidiana de todos los afectados en Vi\u00f1a del Mar y otras partes de Valpara\u00edso.<\/p>\n<p class=\"wp-block-paragraph\"><strong>\u201c\u00a1A todas las v\u00edctimas de los incendios forestales, sean fuertes!\u201d<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"A principios de febrero, incendios forestales devastaron varias \u00e1reas en Valpara\u00edso, Chile. La sequ\u00eda prolongada, las temperaturas altas y los vientos fuertes alimentaron la propagaci\u00f3n r\u00e1pida de incendios que alcanzaron \u00e1reas residenciales. M\u00e1s de 16 000 edificios, incluyendo viviendas, fueron da\u00f1ados, y m\u00e1s de 150 personas perdieron sus vidas. Aproximadamente una tercera parte de Vi\u00f1a&#8230;","protected":false},"author":11,"featured_media":35318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"post-type\/overlay-half-dark.php","format":"standard","meta":{"footnotes":""},"categories":[55,78,58,122],"tags":[],"class_list":["post-241018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sdgs","category-sdgs-no-poverty","category-news","category-no-poverty"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"description\" content=\"La Fundaci\u00f3n Internacional WeLoveU, liderada por la Presidenta Zahng Gil-jah, extendi\u00f3 su apoyo a las v\u00edctimas de incendios forestales en Vi\u00f1a del Mar, Valpara\u00edso, Chile. El 17 y 18 de julio, entregaron 500 cajas de alimentos a 46 cocinas comunitarias operadas por gobiernos locales. Adem\u00e1s, se proporcion\u00f3 ropa el 5 de septiembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"La Fundaci\u00f3n Internacional WeLoveU, liderada por la Presidenta Zahng Gil-jah, extendi\u00f3 su apoyo a las v\u00edctimas de incendios forestales en Vi\u00f1a del Mar, Valpara\u00edso, Chile. El 17 y 18 de julio, entregaron 500 cajas de alimentos a 46 cocinas comunitarias operadas por gobiernos locales. Adem\u00e1s, se proporcion\u00f3 ropa el 5 de septiembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T01:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"l ss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"l ss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/\"},\"author\":{\"name\":\"l ss\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"headline\":\"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile\",\"datePublished\":\"2024-09-05T08:00:00+00:00\",\"dateModified\":\"2026-04-10T01:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/\"},\"wordCount\":683,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_giving_hope_wildfires_chile_240905.jpg\",\"articleSection\":[\"Con los ODS\",\"Fin de la pobreza\",\"Noticias de proyectos\",\"Sin pobreza y hambre cero\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/\",\"name\":\"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_giving_hope_wildfires_chile_240905.jpg\",\"datePublished\":\"2024-09-05T08:00:00+00:00\",\"dateModified\":\"2026-04-10T01:56:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\"},\"description\":\"La Fundaci\u00f3n Internacional WeLoveU, liderada por la Presidenta Zahng Gil-jah, extendi\u00f3 su apoyo a las v\u00edctimas de incendios forestales en Vi\u00f1a del Mar, Valpara\u00edso, Chile. El 17 y 18 de julio, entregaron 500 cajas de alimentos a 46 cocinas comunitarias operadas por gobiernos locales. Adem\u00e1s, se proporcion\u00f3 ropa el 5 de septiembre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_giving_hope_wildfires_chile_240905.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_giving_hope_wildfires_chile_240905.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/giving-hope-wildfires-chile-240905\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/70ce27014e0a04100c14835c4dbe3131\",\"name\":\"l ss\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile - Fundaci\u00f3n Internacional WeLoveU","description":"La Fundaci\u00f3n Internacional WeLoveU, liderada por la Presidenta Zahng Gil-jah, extendi\u00f3 su apoyo a las v\u00edctimas de incendios forestales en Vi\u00f1a del Mar, Valpara\u00edso, Chile. El 17 y 18 de julio, entregaron 500 cajas de alimentos a 46 cocinas comunitarias operadas por gobiernos locales. Adem\u00e1s, se proporcion\u00f3 ropa el 5 de septiembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/","og_locale":"es_ES","og_type":"article","og_title":"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile - Fundaci\u00f3n Internacional WeLoveU","og_description":"La Fundaci\u00f3n Internacional WeLoveU, liderada por la Presidenta Zahng Gil-jah, extendi\u00f3 su apoyo a las v\u00edctimas de incendios forestales en Vi\u00f1a del Mar, Valpara\u00edso, Chile. El 17 y 18 de julio, entregaron 500 cajas de alimentos a 46 cocinas comunitarias operadas por gobiernos locales. Adem\u00e1s, se proporcion\u00f3 ropa el 5 de septiembre.","og_url":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2024-09-05T08:00:00+00:00","article_modified_time":"2026-04-10T01:56:27+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905.jpg","type":"image\/jpeg"}],"author":"l ss","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"l ss","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/"},"author":{"name":"l ss","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"headline":"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile","datePublished":"2024-09-05T08:00:00+00:00","dateModified":"2026-04-10T01:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/"},"wordCount":683,"image":{"@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905.jpg","articleSection":["Con los ODS","Fin de la pobreza","Noticias de proyectos","Sin pobreza y hambre cero"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/","url":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/","name":"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905.jpg","datePublished":"2024-09-05T08:00:00+00:00","dateModified":"2026-04-10T01:56:27+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131"},"description":"La Fundaci\u00f3n Internacional WeLoveU, liderada por la Presidenta Zahng Gil-jah, extendi\u00f3 su apoyo a las v\u00edctimas de incendios forestales en Vi\u00f1a del Mar, Valpara\u00edso, Chile. El 17 y 18 de julio, entregaron 500 cajas de alimentos a 46 cocinas comunitarias operadas por gobiernos locales. Adem\u00e1s, se proporcion\u00f3 ropa el 5 de septiembre.","breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_giving_hope_wildfires_chile_240905.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/giving-hope-wildfires-chile-240905\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"Dando Esperanza a las V\u00edctimas del Incendio Forestal de Vi\u00f1a del Mar en Chile"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/70ce27014e0a04100c14835c4dbe3131","name":"l ss"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/241018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=241018"}],"version-history":[{"count":1,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/241018\/revisions"}],"predecessor-version":[{"id":241020,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/241018\/revisions\/241020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/35318"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=241018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=241018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=241018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}