{"id":240880,"date":"2024-03-18T07:00:00","date_gmt":"2024-03-18T07:00:00","guid":{"rendered":"https:\/\/intlweloveu.org\/womens-history-month-forum-in-usa-240318\/"},"modified":"2026-04-09T06:59:52","modified_gmt":"2026-04-09T06:59:52","slug":"womens-history-month-forum-in-usa-240318","status":"publish","type":"post","link":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/","title":{"rendered":"El liderazgo de la madre crea una sociedad igualitaria e inclusiva"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El mes de marzo se celebra como el <a href=\"https:\/\/www.womenshistorymonth.gov\/\">Mes de la Historia de la Mujer<\/a> en los Estados Unidos, siendo el D\u00eda Internacional de la Mujer, el 8 de marzo, uno de sus momentos m\u00e1s destacados. A lo largo de este mes, se realizan numerosos eventos para reconocer las contribuciones de las mujeres a la fundaci\u00f3n y el desarrollo del pa\u00eds, as\u00ed como para honrar los logros de mujeres pioneras en diversos \u00e1mbitos.<\/p>\n<p class=\"wp-block-paragraph\">El 18 de marzo, WeLoveU organiz\u00f3 un foro especial en la Sala Par\u00eds del Jay Conference en Bryant Park, Nueva York, con la participaci\u00f3n de destacadas l\u00edderes de diversos sectores.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_01.jpg\" alt=\"\" class=\"wp-image-36553\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_01.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_01-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_01-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">Bajo el subt\u00edtulo \u00abCelebrando a las mujeres y madres en el liderazgo en todas las industrias\u00bb, el panel de discusi\u00f3n se dividi\u00f3 en dos rondas: la Ronda 1, titulada \u00abEmpoderando a las mujeres y rompiendo barreras\u00bb, y la Ronda 2, titulada \u00abEl mundo cambiar\u00e1 cuando las personas cambien\u00bb.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"36554\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_02.jpg\" alt=\"\" class=\"wp-image-36554\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_02.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_02-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_02-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Figuras femeninas clave de CNN en la primera discusi\u00f3n del panel:<br>(de izquierda a derecha) Wendy Brundige, Christina Kline, Bernadette Tuazon y Sara Sidner<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" data-id=\"36555\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_03.jpg\" alt=\"\" class=\"wp-image-36555\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_03.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_03-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_03-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Figuras destacadas de los sectores m\u00e9dico, legal y cultural en la segunda discusi\u00f3n del panel:<br>(de izquierda a derecha) Ren\u00e9e Pardo, Jigisha Tamakuwala, Nina Anderson, Inna Swinton y Sara Sidner<\/figcaption><\/figure>\n<\/figure>\n<p class=\"wp-block-paragraph\">Los panelistas presentaron c\u00f3mo superar las barreras sociales enfrentadas por mujeres a medida que se convirtieron en l\u00edderes en sus respectivos campos.<\/p>\n<p class=\"wp-block-paragraph\">Tambi\u00e9n compartieron los factores que influyeron en sus vidas y enfatizaron la importancia de mantener una mentalidad positiva.<\/p>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_04.jpg\" alt=\"\" class=\"wp-image-36559 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_04.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_04-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cCuando mi madre supo que solo le quedaban seis meses de vida, no se desalent\u00f3. M\u00e1s bien, vi que mi mam\u00e1 se gradu\u00f3 de la universidad con un t\u00edtulo, aunque estaba en sus cuarenta. Y eso siempre se qued\u00f3 conmigo contra cualquier circunstancia. Sin importar lo que suceda en la vida, si sigues luchando, realmente puedes llegar a alg\u00fan lugar\u201d.<\/p>\n<p class=\"cite wp-block-paragraph\">Wendy Brundige, Vicepresidenta S\u00e9nior de Estrategia de Contenidos, CNN Digital Worldwide<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_05.jpg\" alt=\"\" class=\"wp-image-36560 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_05.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_05-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cRealmente creo que estando juntas, compartiendo nuestras experiencias, as\u00ed es como aprendemos la una de la otra. Es la camarader\u00eda de mujeres la que realmente disfruto en mi trabajo<strong>\u201d.<\/strong><\/p>\n<p class=\"cite wp-block-paragraph\">Bernadette Tuazon, Directora de Fotograf\u00eda, CNN Digital<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_06.jpg\" alt=\"\" class=\"wp-image-36561 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_06.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_06-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cMuchas de las cosas que hacemos como madres no tienen un nombre o un t\u00edtulo, y la gente quiere que tengas un t\u00edtulo. Creo que este es el desaf\u00edo que enfrentan las mujeres como madres<strong>\u201d.<\/strong><\/p>\n<p class=\"cite wp-block-paragraph\">Inna Swinton, Actriz y Escritora<\/p>\n<\/div>\n<\/div>\n<div class=\"wp-block-media-text is-stacked-on-mobile\">\n<figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_07.jpg\" alt=\"\" class=\"wp-image-36562 size-full\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_07.jpg 700w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_07-500x500.jpg 500w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">\u201cNo tengo hijos propios, pero me considero una madre. Tuve experiencia criando a otros ni\u00f1os con la ayuda de mi mam\u00e1. Creo que cualquiera puede convertirse en madre si tiene el coraz\u00f3n del amor maternal<strong>\u201d.<\/strong><\/p>\n<p class=\"cite wp-block-paragraph\">Dra. Nina Anderson, Presidenta de Tova Community Health<\/p>\n<\/div>\n<\/div>\n<p class=\"wp-block-paragraph\">Aproximadamente 50 miembros de WeLoveU y ciudadanos que asistieron al foro empatizaron con el contenido de la discusi\u00f3n, y exploraron el liderazgo necesario para crear una sociedad igualitaria e inclusiva, as\u00ed como los desaf\u00edos que deben superar las mujeres.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"675\" src=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_08.jpg\" alt=\"\" class=\"wp-image-36563\" srcset=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_08.jpg 1080w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_08-768x480.jpg 768w, https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318_08-800x500.jpg 800w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n<p class=\"wp-block-paragraph\">La exposici\u00f3n de paneles que present\u00f3 las actividades de bienestar de WeLoveU Presidenta Honoraria Zahng Gil-jah\u2014dirigida a crear un mundo donde nadie sea dejado atr\u00e1s y donde la gente viva pac\u00edficamente con respeto mutuo\u2014tambi\u00e9n proporcion\u00f3 gran inspiraci\u00f3n.<\/p>\n<p class=\"wp-block-paragraph\">WeLoveU espera que este foro sirva como una oportunidad significativa para fomentar un cambio positivo para un futuro mejor para las mujeres y el mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"El mes de marzo se celebra como el Mes de la Historia de la Mujer en los Estados Unidos, siendo el D\u00eda Internacional de la Mujer, el 8 de marzo, uno de sus momentos m\u00e1s destacados. A lo largo de este mes, se realizan numerosos eventos para reconocer las contribuciones de las mujeres a la&#8230;","protected":false},"author":9,"featured_media":222628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"post-type\/overlay-half-dark.php","format":"standard","meta":{"footnotes":""},"categories":[125,55,163,58],"tags":[],"class_list":["post-240880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community-well-being","category-sdgs","category-sdgs-gender-equality","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El liderazgo de la madre crea una sociedad igualitaria e inclusiva - Fundaci\u00f3n Internacional WeLoveU<\/title>\n<meta name=\"description\" content=\"El 18 de marzo, la Fundaci\u00f3n Internacional WeLoveU, bajo la direcci\u00f3n de la Presidenta Zahng Gil-jah, organiz\u00f3 un foro en la Sala Par\u00eds de la Conferencia Jay, Bryant Park, Nueva York, EE.UU., para celebrar el Mes de la Historia de la Mujer. El evento, con tema &quot;Celebrando a Mujeres y Madres en Liderazgo en Todas las Industrias&quot;, invit\u00f3 a figuras femeninas prominentes de varios sectores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El liderazgo de la madre crea una sociedad igualitaria e inclusiva - Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"og:description\" content=\"El 18 de marzo, la Fundaci\u00f3n Internacional WeLoveU, bajo la direcci\u00f3n de la Presidenta Zahng Gil-jah, organiz\u00f3 un foro en la Sala Par\u00eds de la Conferencia Jay, Bryant Park, Nueva York, EE.UU., para celebrar el Mes de la Historia de la Mujer. El evento, con tema &quot;Celebrando a Mujeres y Madres en Liderazgo en Todas las Industrias&quot;, invit\u00f3 a figuras femeninas prominentes de varios sectores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Internacional WeLoveU\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-18T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T06:59:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\uc548 \uc9c0\uc601\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\uc548 \uc9c0\uc601\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/\"},\"author\":{\"name\":\"\uc548 \uc9c0\uc601\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/1a1e923e29d2067adcfb1c90e5f0c607\"},\"headline\":\"El liderazgo de la madre crea una sociedad igualitaria e inclusiva\",\"datePublished\":\"2024-03-18T07:00:00+00:00\",\"dateModified\":\"2026-04-09T06:59:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/\"},\"wordCount\":578,\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg\",\"articleSection\":[\"Bienestar de la comunidad\",\"Con los ODS\",\"Igualdad de g\u00e9nero\",\"Noticias de proyectos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/\",\"name\":\"El liderazgo de la madre crea una sociedad igualitaria e inclusiva - Fundaci\u00f3n Internacional WeLoveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg\",\"datePublished\":\"2024-03-18T07:00:00+00:00\",\"dateModified\":\"2026-04-09T06:59:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/1a1e923e29d2067adcfb1c90e5f0c607\"},\"description\":\"El 18 de marzo, la Fundaci\u00f3n Internacional WeLoveU, bajo la direcci\u00f3n de la Presidenta Zahng Gil-jah, organiz\u00f3 un foro en la Sala Par\u00eds de la Conferencia Jay, Bryant Park, Nueva York, EE.UU., para celebrar el Mes de la Historia de la Mujer. El evento, con tema \\\"Celebrando a Mujeres y Madres en Liderazgo en Todas las Industrias\\\", invit\u00f3 a figuras femeninas prominentes de varios sectores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg\",\"contentUrl\":\"https:\\\/\\\/intlweloveu.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"4. \ub2e8\uc5f4\uc7ac \ub450\ub974\uae30\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/womens-history-month-forum-in-usa-240318\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/intlweloveu.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El liderazgo de la madre crea una sociedad igualitaria e inclusiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#website\",\"url\":\"https:\\\/\\\/intlweloveu.org\\\/\",\"name\":\"The Intl. WeLoveU Foundation\",\"description\":\"El Amor de la Madre al Mundo Entero\",\"alternateName\":\"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intlweloveu.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/intlweloveu.org\\\/#\\\/schema\\\/person\\\/1a1e923e29d2067adcfb1c90e5f0c607\",\"name\":\"\uc548 \uc9c0\uc601\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El liderazgo de la madre crea una sociedad igualitaria e inclusiva - Fundaci\u00f3n Internacional WeLoveU","description":"El 18 de marzo, la Fundaci\u00f3n Internacional WeLoveU, bajo la direcci\u00f3n de la Presidenta Zahng Gil-jah, organiz\u00f3 un foro en la Sala Par\u00eds de la Conferencia Jay, Bryant Park, Nueva York, EE.UU., para celebrar el Mes de la Historia de la Mujer. El evento, con tema \"Celebrando a Mujeres y Madres en Liderazgo en Todas las Industrias\", invit\u00f3 a figuras femeninas prominentes de varios sectores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/","og_locale":"es_ES","og_type":"article","og_title":"El liderazgo de la madre crea una sociedad igualitaria e inclusiva - Fundaci\u00f3n Internacional WeLoveU","og_description":"El 18 de marzo, la Fundaci\u00f3n Internacional WeLoveU, bajo la direcci\u00f3n de la Presidenta Zahng Gil-jah, organiz\u00f3 un foro en la Sala Par\u00eds de la Conferencia Jay, Bryant Park, Nueva York, EE.UU., para celebrar el Mes de la Historia de la Mujer. El evento, con tema \"Celebrando a Mujeres y Madres en Liderazgo en Todas las Industrias\", invit\u00f3 a figuras femeninas prominentes de varios sectores.","og_url":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/","og_site_name":"Fundaci\u00f3n Internacional WeLoveU","article_published_time":"2024-03-18T07:00:00+00:00","article_modified_time":"2026-04-09T06:59:52+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg","type":"image\/jpeg"}],"author":"\uc548 \uc9c0\uc601","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\uc548 \uc9c0\uc601","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#article","isPartOf":{"@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/"},"author":{"name":"\uc548 \uc9c0\uc601","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/1a1e923e29d2067adcfb1c90e5f0c607"},"headline":"El liderazgo de la madre crea una sociedad igualitaria e inclusiva","datePublished":"2024-03-18T07:00:00+00:00","dateModified":"2026-04-09T06:59:52+00:00","mainEntityOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/"},"wordCount":578,"image":{"@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg","articleSection":["Bienestar de la comunidad","Con los ODS","Igualdad de g\u00e9nero","Noticias de proyectos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/","url":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/","name":"El liderazgo de la madre crea una sociedad igualitaria e inclusiva - Fundaci\u00f3n Internacional WeLoveU","isPartOf":{"@id":"https:\/\/intlweloveu.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#primaryimage"},"image":{"@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#primaryimage"},"thumbnailUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg","datePublished":"2024-03-18T07:00:00+00:00","dateModified":"2026-04-09T06:59:52+00:00","author":{"@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/1a1e923e29d2067adcfb1c90e5f0c607"},"description":"El 18 de marzo, la Fundaci\u00f3n Internacional WeLoveU, bajo la direcci\u00f3n de la Presidenta Zahng Gil-jah, organiz\u00f3 un foro en la Sala Par\u00eds de la Conferencia Jay, Bryant Park, Nueva York, EE.UU., para celebrar el Mes de la Historia de la Mujer. El evento, con tema \"Celebrando a Mujeres y Madres en Liderazgo en Todas las Industrias\", invit\u00f3 a figuras femeninas prominentes de varios sectores.","breadcrumb":{"@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#primaryimage","url":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg","contentUrl":"https:\/\/intlweloveu.org\/wp-content\/uploads\/2025\/11\/thum_womens_history_month_forum_in_usathum_womens_history_month_forum_in_usa_240318240318.jpg","width":1920,"height":1080,"caption":"4. \ub2e8\uc5f4\uc7ac \ub450\ub974\uae30"},{"@type":"BreadcrumbList","@id":"https:\/\/intlweloveu.org\/es\/womens-history-month-forum-in-usa-240318\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/intlweloveu.org\/es\/"},{"@type":"ListItem","position":2,"name":"El liderazgo de la madre crea una sociedad igualitaria e inclusiva"}]},{"@type":"WebSite","@id":"https:\/\/intlweloveu.org\/#website","url":"https:\/\/intlweloveu.org\/","name":"The Intl. WeLoveU Foundation","description":"El Amor de la Madre al Mundo Entero","alternateName":"\uad6d\uc81c\uc704\ub7ec\ube0c\uc720\uc6b4\ub3d9\ubcf8\ubd80","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intlweloveu.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/intlweloveu.org\/#\/schema\/person\/1a1e923e29d2067adcfb1c90e5f0c607","name":"\uc548 \uc9c0\uc601"}]}},"_links":{"self":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/240880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/comments?post=240880"}],"version-history":[{"count":2,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/240880\/revisions"}],"predecessor-version":[{"id":241663,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/posts\/240880\/revisions\/241663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media\/222628"}],"wp:attachment":[{"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/media?parent=240880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/categories?post=240880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intlweloveu.org\/es\/wp-json\/wp\/v2\/tags?post=240880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}